{"id":6026,"date":"2023-09-21T07:38:32","date_gmt":"2023-09-21T05:38:32","guid":{"rendered":"https:\/\/www.hifab.se\/?p=6026"},"modified":"2023-09-21T07:38:32","modified_gmt":"2023-09-21T05:38:32","slug":"hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter","status":"publish","type":"post","link":"https:\/\/stage-www.hifab.se\/en\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/","title":{"rendered":"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter"},"content":{"rendered":"<p><strong>Efterfr\u00e5gan av strategisk kompetens kring samh\u00e4llsbyggnadsbranschens omst\u00e4llning forts\u00e4tter att \u00f6ka. Nu rekryterar Hifab Advisory ytterligare tre strategikonsulter och dubblar d\u00e4rmed sin storlek f\u00f6r andra g\u00e5ngen p\u00e5 mindre \u00e4n ett \u00e5r.<\/strong><\/p>\n<div id=\"attachment_6027\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6027\" class=\"wp-image-6027 size-large\" src=\"https:\/\/www.hifab.se\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-1024x823.jpg\" alt=\"\" width=\"1024\" height=\"823\" srcset=\"\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-1024x823.jpg 1024w, \/wp-content\/uploads\/2023\/09\/Hifab-Advisory-300x241.jpg 300w, \/wp-content\/uploads\/2023\/09\/Hifab-Advisory-768x617.jpg 768w, \/wp-content\/uploads\/2023\/09\/Hifab-Advisory.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-6027\" class=\"wp-caption-text\">Hifab Advisory<\/p><\/div>\n<p>Hifab Advisory erbjuder sedan november 2022 strategisk r\u00e5dgivning inom aff\u00e4rsstrategi, h\u00e5llbarhet, energistrategi och digitalisering till ledningsgrupper och beslutsfattare inom fastigheter och samh\u00e4llsbyggnad. Trots den utmanande period branschen som helhet befinner sig i \u00e4r responsen och efterfr\u00e5gan fr\u00e5n kunderna fortsatt positiv.<\/p>\n<p>&#8211; Samtidigt som vissa projekt och investeringar bromsar in ser vi att v\u00e5ra kunder \u00e4nd\u00e5 v\u00e4ljer att prioritera de fr\u00e5gor som \u00e4r och kommer bli strategiskt avg\u00f6rande fram\u00e5t \u2013 h\u00e5llbarhet, klimat, digital f\u00f6rm\u00e5ga och energi f\u00f6r att n\u00e4mna n\u00e5gra. Just nu hj\u00e4lper vi m\u00e5nga av v\u00e5ra kunder med klimatriskanalyser, energi- och effektstrategier samt f\u00f6rberedelser inf\u00f6r CSRD och nya regelverk, s\u00e4ger Amanda Tevell, VD p\u00e5 Hifab Advisory.<\/p>\n<p>I slutet av augusti etablerades erbjudandet i G\u00f6teborg och nu st\u00e4rker man upp med ytterligare tre strategikonsulter: Amanda Midhamre, Anna Vanvik och Linda H\u00f6gbacka. De kommer in och kompletterar teamet med h\u00e5llbarhetskompetens, fr\u00e5n Sweco, Ramboll respektive Arcus Development.<\/p>\n<p>&#8211; Det k\u00e4nns riktigt kul att v\u00e5rt erbjudande tagits emot v\u00e4l och att vi de senaste tio m\u00e5naderna haft en s\u00e5 stark tillv\u00e4xt visar tydligt att behovet \u00e4r stort. Vi \u00e4r nu i ett skede d\u00e4r omst\u00e4llningen h\u00e4nder i praktiken, samtidigt som marknaden \u00e4r under ett fortsatt h\u00f6gt f\u00f6r\u00e4ndringstryck drivet av inte minst r\u00e5dande konjunktur. Med v\u00e5r kompetens kan vi hj\u00e4lpa v\u00e5ra kunder att forts\u00e4tta utvecklas i r\u00e4tt riktning och navigera kring de utmaningar och m\u00f6jligheter som nu dyker upp, avslutar Amanda Tevell.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efterfr\u00e5gan av strategisk kompetens kring samh\u00e4llsbyggnadsbranschens omst\u00e4llning forts\u00e4tter att \u00f6ka. Nu rekryterar Hifab Advisory ytterligare tre strategikonsulter och dubblar d\u00e4rmed&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter | Hifab\" \/>\n<meta property=\"og:description\" content=\"Efterfr\u00e5gan av strategisk kompetens kring samh\u00e4llsbyggnadsbranschens omst\u00e4llning forts\u00e4tter att \u00f6ka. Nu rekryterar Hifab Advisory ytterligare tre strategikonsulter och dubblar d\u00e4rmed...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/\" \/>\n<meta property=\"og:site_name\" content=\"Hifab\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-21T05:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stage-www.hifab.se\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emma Johansson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hifab.se\/#website\",\"url\":\"https:\/\/www.hifab.se\/\",\"name\":\"Hifab\",\"description\":\"Oberoende r\u00e5dgivning och ledning\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hifab.se\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg\",\"contentUrl\":\"\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg\",\"width\":400,\"height\":400},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#webpage\",\"url\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/\",\"name\":\"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter | Hifab\",\"isPartOf\":{\"@id\":\"https:\/\/www.hifab.se\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#primaryimage\"},\"datePublished\":\"2023-09-21T05:38:32+00:00\",\"dateModified\":\"2023-09-21T05:38:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.hifab.se\/#\/schema\/person\/d251a72ce4943af3c33cbaa1cc24148e\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hifab.se\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hifab.se\/#\/schema\/person\/d251a72ce4943af3c33cbaa1cc24148e\",\"name\":\"Emma Johansson\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.hifab.se\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/07eec49ee2ade0db650cf9e5074bda38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/07eec49ee2ade0db650cf9e5074bda38?s=96&d=mm&r=g\",\"caption\":\"Emma Johansson\"},\"url\":\"https:\/\/stage-www.hifab.se\/en\/author\/emma-j\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/","og_locale":"en_US","og_type":"article","og_title":"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter | Hifab","og_description":"Efterfr\u00e5gan av strategisk kompetens kring samh\u00e4llsbyggnadsbranschens omst\u00e4llning forts\u00e4tter att \u00f6ka. Nu rekryterar Hifab Advisory ytterligare tre strategikonsulter och dubblar d\u00e4rmed...","og_url":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/","og_site_name":"Hifab","article_published_time":"2023-09-21T05:38:32+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/stage-www.hifab.se\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Emma Johansson","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.hifab.se\/#website","url":"https:\/\/www.hifab.se\/","name":"Hifab","description":"Oberoende r\u00e5dgivning och ledning","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hifab.se\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#primaryimage","inLanguage":"en-US","url":"\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg","contentUrl":"\/wp-content\/uploads\/2023\/09\/Hifab-Advisory-utvald.jpg","width":400,"height":400},{"@type":"WebPage","@id":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#webpage","url":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/","name":"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter | Hifab","isPartOf":{"@id":"https:\/\/www.hifab.se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#primaryimage"},"datePublished":"2023-09-21T05:38:32+00:00","dateModified":"2023-09-21T05:38:32+00:00","author":{"@id":"https:\/\/www.hifab.se\/#\/schema\/person\/d251a72ce4943af3c33cbaa1cc24148e"},"breadcrumb":{"@id":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hifab.se\/hifab-advisory-vaxer-teamet-rekryterar-ytterligare-tre-strategikonsulter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hifab.se\/en\/"},{"@type":"ListItem","position":2,"name":"Hifab Advisory v\u00e4xer teamet \u2013 rekryterar ytterligare tre strategikonsulter"}]},{"@type":"Person","@id":"https:\/\/www.hifab.se\/#\/schema\/person\/d251a72ce4943af3c33cbaa1cc24148e","name":"Emma Johansson","image":{"@type":"ImageObject","@id":"https:\/\/www.hifab.se\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/07eec49ee2ade0db650cf9e5074bda38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07eec49ee2ade0db650cf9e5074bda38?s=96&d=mm&r=g","caption":"Emma Johansson"},"url":"https:\/\/stage-www.hifab.se\/en\/author\/emma-j\/"}]}},"_links":{"self":[{"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/posts\/6026"}],"collection":[{"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/comments?post=6026"}],"version-history":[{"count":2,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/posts\/6026\/revisions"}],"predecessor-version":[{"id":6030,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/posts\/6026\/revisions\/6030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/media\/6028"}],"wp:attachment":[{"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/media?parent=6026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/categories?post=6026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stage-www.hifab.se\/en\/wp-json\/wp\/v2\/tags?post=6026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}